{"id":29913,"date":"2010-04-15T11:01:48","date_gmt":"2010-04-15T11:01:48","guid":{"rendered":""},"modified":"2006-01-01T00:00:00","modified_gmt":"2006-01-01T00:00:00","slug":"3704","status":"publish","type":"post","link":"https:\/\/mboasawa.com\/fr\/3704\/","title":{"rendered":"Arts plastiques : Patrice Kemplo interroge le temps et les traditions"},"content":{"rendered":"<p>Le vernissage de son exposition \u00ab Messages de pays-\u00e2ges \u00bb a eu lieu jeudi dernier \u00e0 Douala.  &#8211; <\/p>\n<p>Qu&rsquo;ai-je fait de ma vie ? Que suis-je devenu  apr&egrave;s cinquante ans ? Qu&rsquo;ai-je retenu ?&raquo; Voil&agrave; quelques interrogations  que suscite le personnage du tableau baptis&eacute; &laquo; Le Temps &raquo; de&nbsp; l&rsquo;artiste plasticien Patrice Kemplo. La toile illustre   un vieillard dans sa cour, face &agrave; un arbre qui se dresse haut devant  lui. L&rsquo;&oelig;uvre porte &eacute;galement l&rsquo;inscription &laquo; 1960-2010 &raquo;. Le tableau&nbsp;  s&rsquo;inspire en fait de la c&eacute;l&eacute;bration du cinquantenaire des ind&eacute;pendances.  Selon Patrice Kemplo, cette &oelig;uvre est une remise en question, un appel &agrave;  la conscience. &laquo; Le Temps &raquo; fait ainsi partie de la deuxi&egrave;me grande  exposition individuelle de Kemplo. Elle est visible dans les locaux de  la galerie Keuko &agrave; Douala jusqu&rsquo;au 22 avril prochain. L&rsquo;artiste a  baptis&eacute; son exposition &laquo; Messages de pays-&acirc;ges&raquo;. A travers les 21 toiles  de cette exposition, Patrice Kemplo &eacute;voque des th&eacute;matiques en rapport  avec l&rsquo;histoire, le temps et la transmission des valeurs  traditionnelles.<\/p>\n<p>Ainsi, le tableau intitul&eacute; &laquo;Danse initiatique &raquo;  met en sc&egrave;ne une danse. La toile illustre trois danseuses v&ecirc;tues de  tenue traditionnelle. Elles se tr&eacute;moussent devant une reine assise,  tenant un chasse-mouche. &laquo; Il existe un v&eacute;ritable probl&egrave;me de  transmission de connaissances au Cameroun, pourtant il est judicieux de  ma&icirc;triser les rituels de la soci&eacute;t&eacute; traditionnelle &raquo;, pense Patrice  Kemplo. A travers &laquo; Messages de pays-&acirc;ges&raquo;, il voudrait ainsi s&rsquo;adresser  &agrave; tous les &acirc;ges. Son message se transcrit &agrave; travers son &oelig;uvre. Les  visiteurs et curieux de l&rsquo;exposition ont &agrave; d&eacute;chiffrer les intentions de  l&rsquo;artiste &agrave; travers les tableaux &laquo; Transmission &raquo;, &laquo; A qui le tour &raquo;, &laquo;  Espace voulu &raquo;, &laquo;Marche spirituelle &raquo;, &laquo; Cit&eacute; perdue &raquo;, entre autres.  Dans son travail, l&rsquo;artiste a utilis&eacute; les mat&eacute;riaux tels la terre, des  coupures de papiers journaux et de vieux sacs de tissus.<\/p>\n<p>A 30  ans, Patrice Kemplo est rendu &agrave; sa deuxi&egrave;me grande exposition  individuelle. Celle-ci intervient apr&egrave;s &laquo; Impressions paysannes &raquo; en  2008. Les &oelig;uvres de l&rsquo;artiste ont &eacute;t&eacute; &eacute;galement pr&eacute;sent&eacute;es &agrave; la faveur  de plusieurs expositions collectives. Patrice Kemplo peint aussi bien le  figuratif que l&rsquo;abstrait. Il dit puiser son inspiration dans les  valeurs &eacute;l&eacute;mentaires de nos coutumes et traditions. Patrice Kemplo  r&eacute;v&egrave;le que l&rsquo;exposition &laquo; Messages de pays-&acirc;ges&raquo;, visible depuis le 08  avril dernier, a &eacute;t&eacute; pr&eacute;par&eacute; pendant huit mois.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"small\">Mathias Mouend&eacute; Ngamo (stagiaire)&nbsp; \t\t<\/span> \t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le vernissage de son exposition \u00ab Messages de pays-\u00e2ges \u00bb a eu lieu jeudi dernier \u00e0 Douala. &#8211; Qu&rsquo;ai-je fait de ma&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[3810],"tags":[],"class_list":["post-29913","post","type-post","status-publish","format-standard","hentry","category-archives"],"_links":{"self":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/posts\/29913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/comments?post=29913"}],"version-history":[{"count":0,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/posts\/29913\/revisions"}],"wp:attachment":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/media?parent=29913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/categories?post=29913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/tags?post=29913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}