{"id":31406,"date":"2008-03-03T15:55:49","date_gmt":"2008-03-03T15:55:49","guid":{"rendered":""},"modified":"2006-01-01T00:00:00","modified_gmt":"2006-01-01T00:00:00","slug":"811","status":"publish","type":"post","link":"https:\/\/mboasawa.com\/fr\/811\/","title":{"rendered":"Proc\u00e8s en sorcellerie pour \u00abapprentis sorciers\u00bb"},"content":{"rendered":"<p><strong><font color=\"#000000\">Yaound&eacute; : <br \/><\/font><\/strong><\/p>\n<hr size=\"1\" color=\"#bbbbbb\" \/> <em>Des verdicts ont d&eacute;j&agrave; &eacute;t&eacute; rendus contre des personnes interpell&eacute;es lors des manifestations.<br \/><em><strong> Lindovi Ndjio (Stagiaire) <\/strong><\/em><\/em><\/p>\n<hr size=\"1\" color=\"#eeffee\" \/> Coaction d&rsquo;activit&eacute;s dangereuses, destruction de bien publics, destruction de bien d&rsquo;autrui, barricades et vagabondages, d&eacute;faut de pi&egrave;ces d&rsquo;identit&eacute;&hellip;Telles sont entre autres les chefs d&rsquo;accusation retenus contre les personnes interpell&eacute;es lors des manifestations qui ont &eacute;maill&eacute; la vie sociale au Cameroun ces derniers jours. Des centaines de jeunes dont des adolescents, des &eacute;tudiants, des &eacute;l&egrave;ves, des ch&ocirc;meurs,&hellip;paient les frais des casses orchestr&eacute;es lors de la crise. Ce 29 f&eacute;vrier 2008 &agrave; Yaound&eacute;, on en est au deuxi&egrave;me jour des proc&egrave;s et la justice camerounaise fait preuve d&rsquo;une diligence qu&rsquo;on lui a rarement reconnue. Diverses sanctions sont d&eacute;j&agrave; prononc&eacute;es : deux ans de prison &agrave; ceux jug&eacute;s jeudi dernier au palais de justice d&rsquo;Ekounou, 15 mois de prison pour certains, des &laquo;d&eacute;lib&eacute;rations prorog&eacute;es au 3 mars 2008&raquo; pour d&rsquo;autres. Jusqu&rsquo;ici, aucun accus&eacute; relax&eacute;. Tous sont reconnus coupables. <\/p>\n<p>Les avocats tirent la conclusion avant la fin du marathon judiciaire : c&rsquo;est une &laquo;parodie de justice&raquo;. Me Abia explique : &laquo; lors de ces enqu&ecirc;tes pr&eacute;liminaires et m&ecirc;me &agrave; l&rsquo;ouverture des proc&egrave;s, on n&rsquo;a permis &agrave; aucun accus&eacute; de se faire assister d&rsquo;un conseil, ni de se constituer une d&eacute;fense. Nous les avons donc surpris en intervenant cette mi journ&eacute;e. C&rsquo;est pourquoi les peines commencent &agrave; baisser&raquo;. Pour Me Armand Bitha, &laquo;nous avons sollicit&eacute; des renvois que l&rsquo;on a rejet&eacute;s cat&eacute;goriquement &raquo;. <\/p>\n<p>Les accus&eacute;s d&eacute;noncent des actes de tortures dont ils ont &eacute;t&eacute; victimes. &laquo;Avec le fusil, ils m&rsquo;ont cogn&eacute; la nuque quand ils m&rsquo;arr&ecirc;taient &raquo;, se plaint No&euml;l Fokam, la vingtaine. &laquo;Nous avons demand&eacute; &agrave; lire les proc&egrave;s verbaux avant de signer, ils ont refus&eacute;&raquo;, ajoute-t-il. Presque tous reconnaissent qu&rsquo;ils &eacute;taient en possession de leurs pi&egrave;ces d&rsquo;identit&eacute; au moment des arrestations. On les a retir&eacute;es lors des enqu&ecirc;tes pr&eacute;liminaires, mais devant le tribunal, on leur reproche la non possession de la pi&egrave;ce. <\/p>\n<p><strong>T&eacute;moins<\/strong><br \/>On aura tout vu et entendu &agrave; l&rsquo;occasion de ces proc&egrave;s. Des audiences fortement militaris&eacute;es, des d&eacute;lib&eacute;rations qui durent plus d&rsquo;une heure de temps, de nombreuses suspensions d&rsquo;audience, des t&eacute;moins qui n&rsquo;existent pas sur les proc&egrave;s verbaux ou que le procureur n&rsquo;a pas &agrave; l&rsquo;ouverture des proc&egrave;s mais qui entre temps surgissent. Exc&eacute;d&eacute;, Me Abia, avocat, a demand&eacute; au procureur de la R&eacute;publique : &laquo; d&rsquo;o&ugrave; sortent ces t&eacute;moins que vous venez d&rsquo;affirmer n&rsquo;avoir pas?&raquo;.<\/p>\n<p>Les d&eacute;bats ont tr&egrave;s souvent achopp&eacute; sur la signification de t&eacute;moin. Quand les diff&eacute;rentes parties s&rsquo;accordent &agrave; dire que &laquo; le t&eacute;moin c&rsquo;est celui qui a vu et entendu une sc&egrave;ne &raquo;, il devient difficile pour ces derniers (policiers et gendarmes) de dire avec exactitude qui ils ont vu en action. Le deuxi&egrave;me adjoint au commissaire de Mendong avoue qu&rsquo; &laquo; il pouvait arriver qu&rsquo;on arr&ecirc;te des innocents parce que quand on arrivait les casseurs fuyaient, et d&rsquo;autres faisaient les faux courageux&raquo;. Egalement, Alain Assamba de la brigade terre de M&eacute;len reconna&icirc;t avoir &laquo;personnellement arr&ecirc;t&eacute; un curieux qui regardait une bagarre &agrave; la Chapelle Obili&raquo;.<\/p>\n<p> Ils se sont plusieurs fois contredits. Confondu par les avocats, le m&ecirc;me Assamba a avou&eacute; qu&rsquo;un accus&eacute; &laquo; &eacute;tait &agrave; bord de son v&eacute;hicule quand on l&rsquo;a interpell&eacute; &raquo;, alors que son coll&egrave;gue vient de dire qu&rsquo; &laquo;il &eacute;tait parmi ceux qui posaient des barricades &raquo;. Joseph Nguefack a &eacute;t&eacute; interpell&eacute; au m&ecirc;me moment au Cradat et &agrave; M&eacute;len par deux gendarmes diff&eacute;rents. <br \/>Ce qui n&rsquo;a eu aucun impact sur le sort de ces jeunes qui, &agrave; entendre les t&eacute;moins, sont pour la plupart des innocents. De quoi donner raison &agrave; une source bien inform&eacute;e qui r&eacute;v&egrave;le que &laquo;les proc&egrave;s sont suivis depuis les hauts lieux d&rsquo;o&ugrave; viennent des instructions fermes&raquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yaound&eacute; : Des verdicts ont d&eacute;j&agrave; &eacute;t&eacute; rendus contre des personnes interpell&eacute;es lors des manifestations. Lindovi Ndjio (Stagiaire) Coaction d&rsquo;activit&eacute;s dangereuses, destruction&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[3810],"tags":[],"class_list":["post-31406","post","type-post","status-publish","format-standard","hentry","category-archives"],"_links":{"self":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/posts\/31406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/comments?post=31406"}],"version-history":[{"count":0,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/posts\/31406\/revisions"}],"wp:attachment":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/media?parent=31406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/categories?post=31406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/tags?post=31406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}