{"id":32003,"date":"2008-10-16T09:41:43","date_gmt":"2008-10-16T09:41:43","guid":{"rendered":""},"modified":"2006-01-01T00:00:00","modified_gmt":"2006-01-01T00:00:00","slug":"1561","status":"publish","type":"post","link":"https:\/\/mboasawa.com\/fr\/1561\/","title":{"rendered":"les temporaires paralysent Camtel"},"content":{"rendered":"<p class=\"surtitre\"> DOUALA <\/p>\n<p><span class=\"surtitre\"><a class=\"titre\"> <\/a><\/span><\/p>\n<p align=\"justify\" class=\"texte\"><span class=\"Style3\"><span class=\"Style32 Style43\"><em>  Les agents gr&eacute;vistes n&rsquo;ont pas rencontr&eacute; le directeur des ressources humaines envoy&eacute; par le directeur g&eacute;n&eacute;ral pour n&eacute;gocier.  <\/em><\/span><\/p>\n<p> Depuis le jeudi 10 octobre 2008, les agents temporaires (environ 300) de la Camtel Littoral manifestent devant la direction provinciale du Littoral (Dpl). D&rsquo;abord consid&eacute;r&eacute;e comme anodine &agrave; ses d&eacute;buts, la manifestation a pris des proportions inqui&eacute;tantes et entra&icirc;ne des cons&eacute;quences dommageables. Le fonctionnement s&rsquo;en trouve paralys&eacute; et les caisses de l&rsquo;entreprise accusent un manque &agrave; gagner important. Les agents en gr&egrave;ve se recrutent en effet affect&eacute;s parmi plusieurs corps de m&eacute;tiers. On y retrouve des secr&eacute;taires de direction, des standardistes, des techniciens de r&eacute;seaux, de transmission, d&rsquo;informatique, d&rsquo;&eacute;lectricit&eacute;, d&rsquo;&eacute;nergie, d&rsquo;Internet Campac, &hellip;). <br \/> Plus encore, cette gr&egrave;ve survient en d&eacute;but du mois, au moment o&ugrave; il fallait entamer la distribution des factures de t&eacute;l&eacute;phones filaires et le r&eacute;tablissement des lignes. &ldquo; Voil&agrave; des gens qui disent r&eacute;clamer l&rsquo;int&eacute;gration et qui nous causent depuis le d&eacute;but de cette gr&egrave;ve un manque &agrave; gagner important &rdquo;, d&eacute;plore un responsable administratif. Une situation qui oblige Mme Achidi Achu Judith Yah, le directeur provincial du Littoral de la Camtel &agrave; multiplier les r&eacute;unions avec ses collaborateurs pour trouver une voie de sortie &agrave; cette crise. Plus que quiconque, elle sait que les temporaires sont un maillon incontournable dans la production des r&eacute;sultats de cette entreprise. Depuis cinq jours de sit-in, les gr&eacute;vistes ne d&eacute;mordent pas. Les pancartes qu&rsquo;ils tiennent bien en &eacute;vidence, r&eacute;sument l&rsquo;essentiel de leurs revendications. Celles-ci tiennent &agrave; quelques messages path&eacute;tiques. &ldquo; Apr&egrave;s 2 &agrave; 10 ans de service quel est notre avenir ? &rdquo; ; &ldquo; La Camtel bafoue notre avenir &rdquo; ; &ldquo; Papa Paul Biya au secours !&rdquo;&hellip;<\/p>\n<p> <strong> Echec de mission ?<\/strong><br \/> Conscient des enjeux, le directeur g&eacute;n&eacute;ral, David Nkotto Emane a d&eacute;p&ecirc;ch&eacute; mardi 14 octobre 2008 &agrave; Douala, le directeur des ressources humaines, Charles Pedene pour n&eacute;gocier. Malheureusement, il n&rsquo;a pas pu rencontrer les agents temporaires. Sa tentative de rencontrer une d&eacute;l&eacute;gation de dix repr&eacute;sentants des agents temporaires a &eacute;chou&eacute;. &ldquo;A l&rsquo;heure actuelle, il n&rsquo;est plus question d&rsquo;envoyer seulement quelques repr&eacute;sentants qui pourraient subir des pressions des responsables. On nous re&ccedil;oit tous, sinon rien&rdquo;, lancent en ch&oelig;ur les agents temporaires. Devant ce refus, l&rsquo;envoy&eacute; de la direction g&eacute;n&eacute;rale et les responsables de la Dpl Camtel se sont rendus &agrave; l&rsquo;inspection du travail. M&ecirc;me la m&eacute;diation de l&rsquo;inspecteur appel&eacute; en rescousse n&rsquo;a pas prosp&eacute;r&eacute;. En d&eacute;sespoir de cause, l&rsquo;inspecteur du travail a propos&eacute; aux gr&eacute;vistes la liquidation de leurs droits. Ce qu&rsquo;ils ont refus&eacute;. &ldquo;L&rsquo;int&eacute;gration ou rien. Pas question de d&eacute;part volontaire &rdquo;, ont-ils r&eacute;pliqu&eacute;. <br \/> Selon ce qui ressort de leurs plaintes, les agents temporaires d&eacute;noncent entre autres, les recrutements s&eacute;lectifs au sein de l&rsquo;entreprise, notamment les 600 recrut&eacute;s en 2005. Au-del&agrave; de ce cas ponctuel, il faut relever qu&rsquo;il y a un conflit latent. Le personnel de l&rsquo;ex-Minpostel revers&eacute; dans les effectifs de Camtel par exemple, d&eacute;nonce des disparit&eacute;s salariales avec celui recrut&eacute; directement par Camtel du fait que le nouvel employeur n&rsquo;avait pas tenu compte de leur anciennet&eacute;. Camtel vient ainsi s&rsquo;ajouter &agrave; la liste d&eacute;j&agrave; longue des entreprises qui connaissent ce type de probl&egrave;me, le Chantier naval, Aes-Sonel, etc. Devant l&rsquo;intransigeance des gr&eacute;vistes, Charles Pedene et Mme Achidi Achu Judith ont &eacute;t&eacute; rappel&eacute;s d&rsquo;urgence &agrave; Yaound&eacute; hier mercredi. Pendant ce temps une d&eacute;l&eacute;gation des gr&eacute;vistes est all&eacute;e remettre leur m&eacute;morandum au gouverneur du Littoral.<\/span>&nbsp;<\/p>\n<p>Par  Mathieu Nathana&euml;l NJOG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DOUALA Les agents gr&eacute;vistes n&rsquo;ont pas rencontr&eacute; le directeur des ressources humaines envoy&eacute; par le directeur g&eacute;n&eacute;ral pour n&eacute;gocier. Depuis le jeudi&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[3810],"tags":[],"class_list":["post-32003","post","type-post","status-publish","format-standard","hentry","category-archives"],"_links":{"self":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/posts\/32003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/comments?post=32003"}],"version-history":[{"count":0,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/posts\/32003\/revisions"}],"wp:attachment":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/media?parent=32003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/categories?post=32003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/tags?post=32003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}