{"id":32629,"date":"2010-01-06T16:28:52","date_gmt":"2010-01-06T16:28:52","guid":{"rendered":""},"modified":"2006-01-01T00:00:00","modified_gmt":"2006-01-01T00:00:00","slug":"2220","status":"publish","type":"post","link":"https:\/\/mboasawa.com\/fr\/2220\/","title":{"rendered":"Pipeline Tchad-Cameroun : 66 milliards de Fcfa de retomb\u00e9es en six ans"},"content":{"rendered":"<p><\/p>\n<p><span class=\"13aria\"> C&rsquo;est ce que le Cameroun a d&eacute;j&agrave; gagn&eacute; selon le Comit&eacute; de pilotage et de suivi de l&rsquo;ol&eacute;oduc.<\/p>\n<p>Pour l&rsquo;exercice 2009, notamment du 1er janvier au 15 novembre dernier, les op&eacute;rations d&rsquo;enl&egrave;vement du p&eacute;trole brut tchadien au terminal de Kome-Kribi, ont permis d&rsquo;&eacute;vacuer 37,44 millions de barils. Sur un volume de 44 enl&egrave;vements de p&eacute;trole effectu&eacute;s au cours de cette p&eacute;riode, l&rsquo;Etat du Cameroun a, au titre du droit de transit, r&eacute;colt&eacute; 15,35 millions de dollars, soit 7,49 milliards de Fcfa. Les administrations concern&eacute;es par la surveillance administrative et le contr&ocirc;le technique des activit&eacute;s li&eacute;es &agrave; l&rsquo;exploitation de l&rsquo;ol&eacute;oduc tchadien, ont indiqu&eacute; lors de la deuxi&egrave;me session du Comit&eacute; de pilotage des pipelines (Cpsp) tenue lme 24 novembre 2009, que depuis sa mise en service en octobre 2003, le pipeline a g&eacute;n&eacute;r&eacute; plus de 66,7 milliards de Fcfa pour le Tr&eacute;sor public camerounais. <\/p>\n<p>Au cours de cette deuxi&egrave;me session du Cpsp qui a pass&eacute; en revue toutes les activit&eacute;s li&eacute;es &agrave; cet ouvrage pendant le r&eacute;cent exercice, le communiqu&eacute; renseigne sur l&rsquo;&eacute;tat de la dette contract&eacute;e par le Cameroun au sujet de la r&eacute;alisation de ce projet. Ainsi, il ressort que sur les 53,4 millions de dollars (plus de 26 milliards de Fcfa) emprunt&eacute;s aupr&egrave;s de la Banque internationale pour la reconstruction et le d&eacute;veloppement (Bird), le pays a d&eacute;j&agrave; rembours&eacute; 32,847 millions de dollars, soit plus de 16 milliards de Fcfa. Le Cameroun a aussi engag&eacute; une op&eacute;ration similaire avec la Banque europ&eacute;enne d&rsquo;investissement (Bei), aupr&egrave;s de qui il a emprunt&eacute; 35,7 millions d&rsquo;euros (plus de 23 milliards de Fcfa). A cette institution, le pays a rembours&eacute; 9,5 milliards de Fcfa.<\/p>\n<p>Des &eacute;tudes d&rsquo;ing&eacute;nierie &eacute;labor&eacute;es en collaboration avec le minist&egrave;re des Finances, Electricity Developpement Corporation (Edc) et Cotco, vont n&eacute;cessiter selon le communiqu&eacute;, un investissement de 3,1 millions de dollars, soit plus de 1,5 milliard de Fcfa. Les fonds qui seront vers&eacute;s enti&egrave;rement par le Cameroun, serviront &agrave; &quot;l&rsquo;adaptation du pipeline Tchad-Cameroun au futur barrage de Lom Pangar &quot;. Il s&rsquo;agira concr&egrave;tement de d&eacute;placer la partie du pipeline qui se trouve sur le site du barrage &agrave; construire, avant sa mise en eau. Pour la s&eacute;curit&eacute; de l&rsquo;ouvrage, apprend-on, le minist&egrave;re de la D&eacute;fense a re&ccedil;u un appui logistique en vue du renforcement du dispositif mis en place par l&rsquo;administration charg&eacute;e de la s&eacute;curisation des installations. <\/p>\n<p><strong>Enl&egrave;vements <\/strong><br \/>Pour m&eacute;moire, lors de la c&eacute;r&eacute;monie d&rsquo;au revoir &agrave; Jacky Lesage, ancien directeur g&eacute;n&eacute;ral de Cotco, organis&eacute;eau dernier trimestre de l&rsquo;ann&eacute;e derni&egrave;re, l&rsquo;administrateur directeur g&eacute;n&eacute;ral de la soci&eacute;t&eacute; nationale des hydrocarbures (Snh), Adolphe Moudiki, par ailleurs pr&eacute;sident du Cpsp, avait indiqu&eacute; que le Cameroun envisageait de r&eacute;viser le contrat portant sur les droits de transit de l&rsquo;ol&eacute;oduc tchadien. Car, trois ans seulement apr&egrave;s la mise en service de l&rsquo;ouvrage, le consortium des soci&eacute;t&eacute;s Exxon mobil, Petronas, et Chevron Texaco, a amorti la totalit&eacute; de ses investissements et emmagasin&eacute; 2300 milliards de Cfca. <\/p>\n<p>Invoquant &quot;la justice &eacute;conomique&quot;, Adolphe Moudiki a soulign&eacute; que &quot;le consortium des soci&eacute;t&eacute;s p&eacute;troli&egrave;res et l&rsquo;Etat du Tchad, ont remarquablement b&eacute;n&eacute;fici&eacute; de l&#8217;embellie des prix sur le march&eacute; p&eacute;trolier international&quot;, tandis que &quot;les revenus du Cameroun ont &eacute;t&eacute; inversement proportionnels&quot;. Aussi avait-t-il plaid&eacute; pour une solution mutuellement b&eacute;n&eacute;fique &agrave; toutes les parties, &quot;dans les meilleurs d&eacute;lais&quot;. Entre la mise en service du pipeline le 3 octobre 2003 et le mois de mars 2009, 221 enl&egrave;vements ont &eacute;t&eacute; effectu&eacute;s pour un total de 201 millions de barils. La loi camerounaise du 5 ao&ucirc;t 1996 portant r&eacute;gime du transport des hydrocarbures par pipeline en provenance de pays tiers, fixe le montant du droit de transit, qui est une taxe exigible mensuellement, assise sur les quantit&eacute;s de p&eacute;trole brut transport&eacute;es durant le mois pr&eacute;c&eacute;dent. Ces quantit&eacute;s sont arr&ecirc;t&eacute;es au moment de l&rsquo;enl&egrave;vement du brut sur le terminal de Kome-Kribi. Le taux unitaire fix&eacute; par baril de p&eacute;trole est rest&eacute; inchang&eacute;, malgr&eacute; l&#8217;embellie des prix du p&eacute;trole brut sur le march&eacute; international.<\/p>\n<p><em>Pierre C&eacute;lestin Atangana<\/em> <\/span>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est ce que le Cameroun a d&eacute;j&agrave; gagn&eacute; selon le Comit&eacute; de pilotage et de suivi de l&rsquo;ol&eacute;oduc. Pour l&rsquo;exercice 2009, notamment&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[3810],"tags":[],"class_list":["post-32629","post","type-post","status-publish","format-standard","hentry","category-archives"],"_links":{"self":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/posts\/32629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/comments?post=32629"}],"version-history":[{"count":0,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/posts\/32629\/revisions"}],"wp:attachment":[{"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/media?parent=32629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/categories?post=32629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mboasawa.com\/fr\/wp-json\/wp\/v2\/tags?post=32629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}